{"id":27,"date":"2023-07-20T13:40:56","date_gmt":"2023-07-20T13:40:56","guid":{"rendered":"https:\/\/ayvaz.sipa.web.tr\/?page_id=27"},"modified":"2024-12-13T06:52:59","modified_gmt":"2024-12-13T06:52:59","slug":"home","status":"publish","type":"page","link":"https:\/\/www.ayvaz.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"slider-wrapper relative\" id=\"slider-1741460549\" >\n    <div class=\"slider slider-nav-dots-simple slider-nav-simple slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": false,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\t<section class=\"section dark is-full-height\" id=\"section_1870908659\">\n\t\t<div class=\"bg section-bg fill bg-fill  \" >\n\n\t\t\t\n\t\t\t<button class=\"scroll-for-more z-5 icon absolute bottom h-center\" aria-label=\"Scroll for more\"><i class=\"icon-angle-down\" style=\"font-size:42px;\" ><\/i><\/button>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\" style=\"max-width:1300px\" id=\"row-1529160580\">\n\n\n\t<div id=\"col-1995703423\" class=\"col medium-8 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2552970834\" class=\"text\">\n\t\t\n\n<h6>FROM LOCAL TO GLOBAL<\/h6>\n\t\t\n<style>\n#text-2552970834 {\n  font-size: 1.35rem;\n  text-align: left;\n}\n@media (min-width:550px) {\n  #text-2552970834 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1537795108\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1537795108 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\" style=\"max-width:1300px\" id=\"row-1816359837\">\n\n\n\t<div id=\"col-1798302919\" class=\"col medium-8 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-778733137\" class=\"text\">\n\t\t\n\n<h1 class=\"uppercase\">100 + COUNTRIES<\/h1>\n\t\t\n<style>\n#text-778733137 {\n  font-size: 1.5rem;\n  text-align: left;\n}\n@media (min-width:550px) {\n  #text-778733137 {\n    font-size: 1.7rem;\n  }\n}\n@media (min-width:850px) {\n  #text-778733137 {\n    font-size: 2.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1798302919 > .col-inner {\n  margin: -45px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-391672957\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-391672957 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\" style=\"max-width:1300px\" id=\"row-542475405\">\n\n\n\t<div id=\"col-2048132331\" class=\"col medium-8 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3086456986\" class=\"text\">\n\t\t\n\n<p>We offer solutions to 100+ countries with our factories in 5 countries and 13 international sales offices to meet your demand. We aim to be \"Globally Local\" solution partner.<\/p>\n\t\t\n<style>\n#text-3086456986 {\n  font-size: 0.8rem;\n  text-align: left;\n}\n@media (min-width:550px) {\n  #text-3086456986 {\n    font-size: 1.1rem;\n  }\n}\n@media (min-width:850px) {\n  #text-3086456986 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"stack-1137925981\" class=\"stack stack-row justify-start items-start\">\n\t\t\n\n<a href=\"\/en\/\/about-us\/\" target=\"_self\" class=\"button white is-outline is-smaller\"  style=\"padding:5px 30px 5px 30px;\">\n    <span>ABOUT US<\/span>\n  <i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\n\t\t\n<style>\n#stack-1137925981 > * {\n  --stack-gap: 0rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2048132331 > .col-inner {\n  margin: -50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2048132331 > .col-inner {\n    margin: -60px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1870908659 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 450px;\n}\n#section_1870908659 .section-bg.bg-loaded {\n  background-image: url(https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/slider-ayvaz-2.jpeg);\n}\n#section_1870908659 .section-bg {\n  background-position: 58% 47%;\n}\n#section_1870908659 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1870908659 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n@media (min-width:550px) {\n  #section_1870908659 {\n    min-height: 650px;\n  }\n}\n@media (min-width:850px) {\n  #section_1870908659 {\n    min-height: 100vh;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section dark is-full-height\" id=\"section_985235845\">\n\t\t<div class=\"bg section-bg fill bg-fill  \" >\n\n\t\t\t\n\t\t\t<button class=\"scroll-for-more z-5 icon absolute bottom h-center\" aria-label=\"Scroll for more\"><i class=\"icon-angle-down\" style=\"font-size:42px;\" ><\/i><\/button>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\" style=\"max-width:1300px\" id=\"row-1124819104\">\n\n\n\t<div id=\"col-1294154952\" class=\"col medium-8 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2862103971\" class=\"text\">\n\t\t\n\n<h6>THE TRUE POWER OF OUR BRAND<\/h6>\n\t\t\n<style>\n#text-2862103971 {\n  font-size: 1.35rem;\n}\n@media (min-width:550px) {\n  #text-2862103971 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1967971662\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1967971662 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\" style=\"max-width:1300px\" id=\"row-1458854299\">\n\n\n\t<div id=\"col-1410865484\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2601937551\" class=\"text\">\n\t\t\n\n<h1 class=\"uppercase\">SUPERIOR PRODUCTION EXPERIENCE<\/h1>\n\t\t\n<style>\n#text-2601937551 {\n  font-size: 1.1rem;\n}\n@media (min-width:550px) {\n  #text-2601937551 {\n    font-size: 1.4rem;\n  }\n}\n@media (min-width:850px) {\n  #text-2601937551 {\n    font-size: 2.05rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1410865484 > .col-inner {\n  margin: -45px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1841611825\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1841611825 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\" style=\"max-width:1300px\" id=\"row-2099712262\">\n\n\n\t<div id=\"col-864806516\" class=\"col medium-8 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1858271335\" class=\"text\">\n\t\t\n\n<p>Ayvaz has been manufacturing for more than 70 years using the latest technologies to provide you the best.<\/p>\n\t\t\n<style>\n#text-1858271335 {\n  font-size: 0.85rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-864806516 > .col-inner {\n  margin: -50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-864806516 > .col-inner {\n    margin: -60px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_985235845 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 450px;\n}\n#section_985235845 .section-bg.bg-loaded {\n  background-image: url(https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/slider-ayvaz-1.jpeg);\n}\n#section_985235845 .section-bg {\n  background-position: 62% 63%;\n}\n#section_985235845 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_985235845 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n@media (min-width:550px) {\n  #section_985235845 {\n    min-height: 650px;\n  }\n}\n@media (min-width:850px) {\n  #section_985235845 {\n    min-height: 100vh;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\t<section class=\"section\" id=\"section_948539077\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-1785179628\">\n\n\n\t<div id=\"col-2142442086\" class=\"col medium-8 small-11 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1188366678\" class=\"text\">\n\t\t\n\n<h4>QUALITY OF OUR<span data-text-color=\"primary\"> PRODUCTS<\/span>\n<\/h4>\n\t\t\n<style>\n#text-1188366678 {\n  font-size: 1.35rem;\n}\n@media (min-width:550px) {\n  #text-1188366678 {\n    font-size: 1.8rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3134176807\" class=\"text\">\n\t\t\n\n<p>Ayvaz operates its production complying with the standards that recognized by the most important international bodies and industrial associations.<\/p>\n\t\t\n<style>\n#text-3134176807 {\n  font-size: 1rem;\n}\n@media (min-width:550px) {\n  #text-3134176807 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:50px;background-color:rgb(68, 68, 68);\"><\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-503729619\">\n\n\n\t<div id=\"col-884894411\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1979889813\" >\n    <div class=\"slider slider-nav-simple slider-nav-normal slider-nav-light slider-nav-outside slider-style-focus slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": true,\n            \"wrapAround\": true,\n            \"autoPlay\": 4000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/aeq.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/eco.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/aga.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/asme.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/asme_u.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/asme_u2.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/bsi-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/bureau_veritas-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/ce-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 232.02150537634px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/01\/dn5670a5e0-logo-about-.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:110px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/dvgw-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/eac-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/fm-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/iep_atex-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/kalitest_iso9001_2015-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/kalitest_iso27001_2013-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/lloyds_register-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/nf-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/nippon-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/pmpc-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/rina-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><a class=\"ux-logo-link block image-\" title=\"\"  href=\"https:\/\/www.ayvaz.com\/en\/downloads-system-certificate\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/tse-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/tsek-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/turk_loydu-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/ul-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/vds-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/wras-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-884894411 > .col-inner {\n  margin: -50px 0px -90px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_948539077 {\n  padding-top: 50px;\n  padding-bottom: 50px;\n  background-color: rgb(249, 249, 250);\n}\n#section_948539077 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_948539077 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_287370484\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse row-full-width align-middle\"  id=\"row-1112084301\">\n\n\n\t<div id=\"col-101677723\" class=\"col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-464840439\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-464840439 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n#banner-464840439 .bg.bg-loaded {\n  background-image: url(https:\/\/www.ayvaz.com\/wp-content\/uploads\/2023\/07\/02-600x400.jpg);\n}\n#banner-464840439 .bg {\n  background-position: 100% 49%;\n}\n#banner-464840439 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-464840439 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n@media (min-width:550px) {\n  #banner-464840439 {\n    padding-top: 500px;\n  }\n}\n@media (min-width:850px) {\n  #banner-464840439 {\n    padding-top: 700px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1753506118\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-1173165976\">\n\n\n\t<div id=\"col-1374432970\" class=\"col medium-10 small-11 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-249830184\" class=\"text\">\n\t\t\n\n<h4> REFERENCES \n<\/h4>\n\t\t\n<style>\n#text-249830184 {\n  font-size: 1.35rem;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-249830184 {\n    font-size: 1.8rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1611533075\" class=\"text\">\n\t\t\n\n<p>We have our signature on giant projects.\n<\/p>\n\t\t\n<style>\n#text-1611533075 {\n  font-size: 1rem;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-1611533075 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:50px;background-color:rgb(68, 68, 68);\"><\/div><\/div>\n\n\t<div id=\"text-1199044223\" class=\"text\">\n\t\t\n\n<p>Ayvaz brings reliable solutions for decades, expanding its area of activity with new products and new investments. From giant petrochemical plants to hydroelectric power plants, Ayvaz's solutions are taking place in various sectors and industries worldwide.\n<\/p>\n<p>Ayvaz is a member of Association Euro-Qualiflex (AEQ) which is the association of the leading European manufacturers of flexible metal hoses, bellows and expansion joints. We export our high-quality products to 100 countries and we've provided solutions for hundreds of thousands projects so far.<\/p>\n\t\t\n<style>\n#text-1199044223 {\n  font-size: 1rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1837201099\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1837201099 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"\/en\/references\/\" target=\"_self\" class=\"button primary is-smaller\"  style=\"padding:5px 30px 5px 30px;\">\n    <span>LEARN MORE<\/span>\n  <i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\t<div id=\"gap-1373448439\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1373448439 {\n  padding-top: 0px;\n}\n@media (min-width:550px) {\n  #gap-1373448439 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1173165976 > .col > .col-inner {\n  padding: 20px 0px 20px 0px;\n}\n@media (min-width:550px) {\n  #row-1173165976 > .col > .col-inner {\n    padding: 60px 0px 60px 0px;\n  }\n}\n@media (min-width:850px) {\n  #row-1173165976 > .col > .col-inner {\n    padding: 60px 0px 40px 0px;\n  }\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1112084301 > .col > .col-inner {\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_287370484 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(255,255,255);\n}\n#section_287370484 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_287370484 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_408429481\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-2084977857\">\n\n\n\t<div id=\"col-1888982036\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1117934208\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1117934208 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3001814402\" class=\"text\">\n\t\t\n\n<h4>NEWS AT<span data-text-color=\"primary\"> AYVAZ<\/span>\n<\/h4>\n\t\t\n<style>\n#text-3001814402 {\n  font-size: 1.35rem;\n  line-height: 0.75;\n}\n@media (min-width:550px) {\n  #text-3001814402 {\n    font-size: 1.8rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3143872069\" class=\"text\">\n\t\t\n\n<p>Find the latest news about Ayvaz here.\n<\/p>\n\t\t\n<style>\n#text-3143872069 {\n  font-size: 0.95rem;\n  line-height: 0.75;\n}\n@media (min-width:550px) {\n  #text-3143872069 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:50px;background-color:rgb(68, 68, 68);\"><\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-728036178\">\n\n\n\t<div id=\"col-676724171\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.ayvaz.com\/en\/ayvaz-to-exhibit-at-big-5-construct-saudi-2026\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"761\" height=\"400\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber-761x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber-761x400.jpg 761w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber-1400x736.jpg 1400w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber-768x404.jpg 768w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber-1536x807.jpg 1536w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber-300x158.jpg 300w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber-600x315.jpg 600w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/08\/BIG5-Saudi-25-08-26_haber.jpg 1560w\" sizes=\"auto, (max-width: 761px) 100vw, 761px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Ayvaz to Exhibit at Big 5 Construct Saudi 2026<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Ayvaz will take part in Big 5 Construct Saudi 2026, bringing its solutions for construction, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.ayvaz.com\/en\/ayvaz-to-exhibit-at-nfpa-conference-expo-2026\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"761\" height=\"400\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26-761x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26-761x400.jpg 761w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26-1400x736.jpg 1400w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26-768x404.jpg 768w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26-1536x807.jpg 1536w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26-300x158.jpg 300w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26-600x315.jpg 600w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/06\/NFPA-fuari-haberler-17-06-26.jpg 1560w\" sizes=\"auto, (max-width: 761px) 100vw, 761px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Ayvaz to Exhibit at NFPA Conference &#038; Expo 2026<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Ayvaz is pleased to announce its participation in the NFPA Conference &amp; Expo 2026, one [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.ayvaz.com\/en\/ayvaz-will-participate-in-interschutz-2026\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"761\" height=\"400\" src=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26-761x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26-761x400.jpg 761w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26-1400x736.jpg 1400w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26-768x404.jpg 768w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26-1536x807.jpg 1536w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26-300x158.jpg 300w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26-600x315.jpg 600w, https:\/\/www.ayvaz.com\/wp-content\/uploads\/2026\/05\/interschutz-fuari-duyuru-fuar-haberler-gorseli-15-05-26.jpg 1560w\" sizes=\"auto, (max-width: 761px) 100vw, 761px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Ayvaz Will Participate in INTERSCHUTZ 2026<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">As Ayvaz, we are pleased to announce our participation in INTERSCHUTZ 2026, one of the [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_408429481 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(249, 249, 250);\n}\n#section_408429481 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_408429481 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n@media (min-width:550px) {\n  #section_408429481 {\n    padding-top: 50px;\n    padding-bottom: 50px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ayvaz.com\/en\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ayvaz.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ayvaz.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ayvaz.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ayvaz.com\/en\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/www.ayvaz.com\/en\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ayvaz.com\/en\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}